{"id":186912,"date":"2024-05-02T06:15:28","date_gmt":"2024-05-02T05:15:28","guid":{"rendered":"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/"},"modified":"2026-05-13T11:10:54","modified_gmt":"2026-05-13T10:10:54","slug":"logitech-webcam-c920s-pro-fhd-1080p-30fps","status":"publish","type":"product","link":"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/","title":{"rendered":"Logitech Webcam C920s PRO FHD 1080P 30fps"},"content":{"rendered":"<p style=\"text-align: left;\">&nbsp;<\/p>\n<table class=\"tabla_caracteristicas k-table\" width=\"100%\">\n<tbody>\n<tr>\n<td valign=\"top\"><strong>Marca<\/strong><\/td>\n<td>Logitech<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\"><strong>Modelo<\/strong><\/td>\n<td><strong>960-001252<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\"><strong>Caracter&iacute;sticas<\/strong><\/td>\n<td><strong>Especificaciones<\/strong><br \/>&#8211; Resoluci&oacute;n m&aacute;x.: 1080p\/30 fps &#8211; 720p\/30 fps<br \/>&#8211; Tipo de enfoque: autom&aacute;tico<br \/>&#8211; Micr&oacute;fono integrado: est&eacute;reo<br \/>&#8211; Clip universal compatible con tr&iacute;podes para monitores, pantallas LCD o port&aacute;tiles<br \/>&#8211; Longitud de cable: 1,5 m<br \/><strong>Requisitos del sistema<\/strong><br \/>Compatible con:<br \/>&#8211; Windows&reg; 10 o posterior, Windows 8, Windows 7<br \/>&#8211; Funciona en modo USB Video Device Class (UVC) con clientes de videoconferencia compatibles:<br \/>&nbsp; macOS 10.10 o posterior<br \/>&nbsp; XBox One&trade;<br \/>&nbsp; Chrome OS&trade;<br \/>&nbsp; Android&trade; v 5.0 o posterior<br \/>&nbsp; Puerto USB<br \/>&nbsp; Conexi&oacute;n a Internet<br \/>&#8211; Compatibilidad con plataformas:<br \/>&nbsp; Skype&trade;<br \/>&nbsp; Google Hangouts&trade;<br \/>&nbsp; FaceTime para Mac<br \/><strong>Dimensiones<\/strong><br \/>&#8211; Sin clip<br \/>&nbsp; Alto x Ancho x Prof: 29 mm x 94 mm x 24 mm<br \/>&#8211; Con clip<br \/>&nbsp; Alto x Ancho x Prof: 43,3 mm x 94 mm x 71 mm<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\"><strong>Fecha de revisi&oacute;n<\/strong><\/td>\n<td>16-11-2020 por MPM<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Marca Logitech Modelo 960-001252 Caracter&iacute;sticas Especificaciones&#8211; Resoluci&oacute;n m&aacute;x.: 1080p\/30 fps &#8211; 720p\/30 fps&#8211; Tipo de enfoque: autom&aacute;tico&#8211; Micr&oacute;fono integrado: est&eacute;reo&#8211; Clip universal compatible con tr&iacute;podes para monitores, pantallas LCD o port&aacute;tiles&#8211; Longitud de cable: 1,5 mRequisitos del sistemaCompatible con:&#8211; Windows&reg; 10 o posterior, Windows 8, Windows 7&#8211; Funciona en modo USB Video Device Class [&hellip;]<\/p>\n","protected":false},"featured_media":92933,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[1610,1484,1609],"product_tag":[1423,827,626],"class_list":{"0":"post-186912","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-camaras-web-video-dispositivos-dispositivos","7":"product_cat-dispositivos","8":"product_cat-video-dispositivos","9":"product_tag-1423","10":"product_tag-cwb","11":"product_tag-logitech","12":"desktop-align-left","13":"tablet-align-left","14":"mobile-align-left","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Logitech Webcam C920s PRO FHD 1080P 30fps - Setnology<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logitech Webcam C920s PRO FHD 1080P 30fps\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Marca Logitech Modelo 960-001252 Caracter&iacute;sticas Especificaciones&#8211; Resoluci&oacute;n m&aacute;x.: 1080p\/30 fps &#8211; 720p\/30 fps&#8211; Tipo de enfoque: autom&aacute;tico&#8211; Micr&oacute;fono integrado: est&eacute;reo&#8211; Clip universal compatible con tr&iacute;podes para monitores, pantallas LCD o port&aacute;tiles&#8211; Longitud de cable: 1,5 mRequisitos del sistemaCompatible con:&#8211; Windows&reg; 10 o posterior, Windows 8, Windows 7&#8211; Funciona en modo USB Video Device Class [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/\" \/>\n<meta property=\"og:site_name\" content=\"Setnology\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:10:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/08\/FVPCWB0132_800.jpg?fit=800%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/logitech-webcam-c920s-pro-fhd-1080p-30fps\\\/\",\"url\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/logitech-webcam-c920s-pro-fhd-1080p-30fps\\\/\",\"name\":\"Logitech Webcam C920s PRO FHD 1080P 30fps - Setnology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/logitech-webcam-c920s-pro-fhd-1080p-30fps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/logitech-webcam-c920s-pro-fhd-1080p-30fps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/FVPCWB0132_800.jpg?fit=800%2C800&ssl=1\",\"datePublished\":\"2024-05-02T05:15:28+00:00\",\"dateModified\":\"2026-05-13T10:10:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/logitech-webcam-c920s-pro-fhd-1080p-30fps\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/logitech-webcam-c920s-pro-fhd-1080p-30fps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/logitech-webcam-c920s-pro-fhd-1080p-30fps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/FVPCWB0132_800.jpg?fit=800%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/FVPCWB0132_800.jpg?fit=800%2C800&ssl=1\",\"width\":800,\"height\":800,\"caption\":\"C\u00e1maras web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/logitech-webcam-c920s-pro-fhd-1080p-30fps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/setnology.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Logitech Webcam C920s PRO FHD 1080P 30fps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#website\",\"url\":\"https:\\\/\\\/setnology.es\\\/\",\"name\":\"Setnology\",\"description\":\"Servicios de Expansi\u00f3n Tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/setnology.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#organization\",\"name\":\"Setnology\",\"url\":\"https:\\\/\\\/setnology.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1\",\"width\":995,\"height\":258,\"caption\":\"Setnology\"},\"image\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Logitech Webcam C920s PRO FHD 1080P 30fps - Setnology","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/","og_locale":"es_ES","og_type":"article","og_title":"Logitech Webcam C920s PRO FHD 1080P 30fps","og_description":"&nbsp; Marca Logitech Modelo 960-001252 Caracter&iacute;sticas Especificaciones&#8211; Resoluci&oacute;n m&aacute;x.: 1080p\/30 fps &#8211; 720p\/30 fps&#8211; Tipo de enfoque: autom&aacute;tico&#8211; Micr&oacute;fono integrado: est&eacute;reo&#8211; Clip universal compatible con tr&iacute;podes para monitores, pantallas LCD o port&aacute;tiles&#8211; Longitud de cable: 1,5 mRequisitos del sistemaCompatible con:&#8211; Windows&reg; 10 o posterior, Windows 8, Windows 7&#8211; Funciona en modo USB Video Device Class [&hellip;]","og_url":"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/","og_site_name":"Setnology","article_modified_time":"2026-05-13T10:10:54+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/08\/FVPCWB0132_800.jpg?fit=800%2C800&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/","url":"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/","name":"Logitech Webcam C920s PRO FHD 1080P 30fps - Setnology","isPartOf":{"@id":"https:\/\/setnology.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/#primaryimage"},"image":{"@id":"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/08\/FVPCWB0132_800.jpg?fit=800%2C800&ssl=1","datePublished":"2024-05-02T05:15:28+00:00","dateModified":"2026-05-13T10:10:54+00:00","breadcrumb":{"@id":"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/#primaryimage","url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/08\/FVPCWB0132_800.jpg?fit=800%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/08\/FVPCWB0132_800.jpg?fit=800%2C800&ssl=1","width":800,"height":800,"caption":"C\u00e1maras web"},{"@type":"BreadcrumbList","@id":"https:\/\/setnology.es\/index.php\/producto\/logitech-webcam-c920s-pro-fhd-1080p-30fps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/setnology.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/setnology.es\/index.php\/tienda\/"},{"@type":"ListItem","position":3,"name":"Logitech Webcam C920s PRO FHD 1080P 30fps"}]},{"@type":"WebSite","@id":"https:\/\/setnology.es\/#website","url":"https:\/\/setnology.es\/","name":"Setnology","description":"Servicios de Expansi\u00f3n Tecnol\u00f3gica","publisher":{"@id":"https:\/\/setnology.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/setnology.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/setnology.es\/#organization","name":"Setnology","url":"https:\/\/setnology.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/setnology.es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2021\/10\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1","contentUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2021\/10\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1","width":995,"height":258,"caption":"Setnology"},"image":{"@id":"https:\/\/setnology.es\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/186912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/186912\/revisions"}],"predecessor-version":[{"id":264287,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/186912\/revisions\/264287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/media\/92933"}],"wp:attachment":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/media?parent=186912"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_brand?post=186912"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_cat?post=186912"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_tag?post=186912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}