{"id":205587,"date":"2026-07-11T05:10:04","date_gmt":"2026-07-11T04:10:04","guid":{"rendered":"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/"},"modified":"2026-07-11T06:10:38","modified_gmt":"2026-07-11T05:10:38","slug":"iggual-pantalla-electrica-169-110-243x137-cm","status":"publish","type":"product","link":"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/","title":{"rendered":"iggual Pantalla el\u00e9ctrica 16:9 110&#8243; 243&#215;137 cm"},"content":{"rendered":"<p style=\"text-align: left;\">\n<p data-end=\"705\" data-start=\"116\">La pantalla el&eacute;ctrica <strong data-end=\"150\" data-start=\"138\">PSIES243<\/strong> de iggual es una apuesta segura para quienes buscan calidad y comodidad en sus presentaciones. Con un formato panor&aacute;mico de 265&#215;149 cm (16:9), ofrece una visualizaci&oacute;n amplia y envolvente, ideal para aulas, oficinas o salas de reuniones. Su superficie de 4 capas mejora el contraste y la nitidez de la imagen, asegurando una proyecci&oacute;n m&aacute;s viva y definida. Gracias a su accionamiento el&eacute;ctrico con mando a distancia y pulsador en pared, su uso es &aacute;gil y c&oacute;modo. Se instala f&aacute;cilmente en techo o pared y es compatible con una gran variedad de proyectores.<\/p>\n<p data-end=\"846\" data-start=\"707\">Conf&iacute;a en iggual para tu d&iacute;a a d&iacute;a profesional: soluciones tecnol&oacute;gicas que destacan por su innovaci&oacute;n, calidad, durabilidad y una excelente relaci&oacute;n calidad-precio, siempre con un soporte cercano y fiable.<\/p>\n<p><\/p>\n<table class=\"tabla_caracteristicas k-table\" width=\"100%\">\n<tr>\n<td><strong>Marca<\/strong><\/td>\n<td>iggual<\/td>\n<\/tr>\n<tr>\n<td><strong>Modelo<\/strong><\/td>\n<td><strong>PSIPS243<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>Uso<\/strong><\/td>\n<td>Pantalla para proyector<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\"><strong>Caracter&iacute;sticas<\/strong><\/td>\n<td>&#8211; Formato 16:9.<br \/>\t\t\t&#8211; &Aacute;rea visible de&nbsp;110&#8243;&nbsp;(243 x 137 cm)<br \/>\t\t\t&#8211; Bordes negros de 4 cm<br \/>\t\t\t&#8211; Carcasa blanca y a prueba de polvo<br \/>\t\t\t&#8211; Apto para pared y techo<br \/>\t\t\t&#8211; Parte trasera en negro para mayor refracci&oacute;n de la luz<br \/>\t\t\t&#8211; Muy buena planeidad y tensi&oacute;n gracias al grosor de la tela<br \/>\t\t\t&#8211; Voltaje 230 VAC- Frecuencia 50Hz<br \/>\t\t\t&#8211; Salida del cable de alimentaci&oacute;n por el lado izquierdo visto desde frente de la pantalla<br \/>\t\t\t&#8211; Incluye control de pared y mando remoto infrarrojo (IR)<br \/>\t\t\t&#8211; Factor de ganancia de 1.0, ideal para cine en casa y presentaciones<br \/>\t\t\t&#8211; La ca&iacute;da de la pantalla puede ser frenada en cualquier punto, por lo que se puede ajustar la longitud de la pantalla a cualquier formato.<br \/>\t\t\t&#8211; La barra inferior queda al ras con la carcasa<br \/>\t\t\t&#8211; Ideal para cualquier tipo de proyector, SVGA, XGA, 3D, HD, Full HD y 4K<br \/>\t\t\t&#8211; Dimensiones del cajet&iacute;n: 272 x 10 x 10 cm<br \/>\t\t\t&#8211;&nbsp;NOTA IMPORTANTE: no incluye torniller&iacute;a, tacos ni ganchos para su instalaci&oacute;n<\/td>\n<\/tr>\n<tr>\n<td><strong>Fecha de revisi&oacute;n<\/strong><\/td>\n<td>04-02-2026 por SB<\/td>\n<\/tr>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>La pantalla el&eacute;ctrica PSIES243 de iggual es una apuesta segura para quienes buscan calidad y comodidad en sus presentaciones. Con un formato panor&aacute;mico de 265&#215;149 cm (16:9), ofrece una visualizaci&oacute;n amplia y envolvente, ideal para aulas, oficinas o salas de reuniones. Su superficie de 4 capas mejora el contraste y la nitidez de la imagen, [&hellip;]<\/p>\n","protected":false},"featured_media":205588,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[1484,1674,1673],"product_tag":[530,529,907],"class_list":["post-205587","product","type-product","status-publish","has-post-thumbnail","product_cat-dispositivos","product_cat-pantallas-proyeccion-dispositivos","product_cat-proyeccion-dispositivos","product_tag-530","product_tag-iggual","product_tag-pay","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>iggual Pantalla el\u00e9ctrica 16:9 110&quot; 243x137 cm - Setnology<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"iggual Pantalla el\u00e9ctrica 16:9 110&quot; 243x137 cm\" \/>\n<meta property=\"og:description\" content=\"La pantalla el&eacute;ctrica PSIES243 de iggual es una apuesta segura para quienes buscan calidad y comodidad en sus presentaciones. Con un formato panor&aacute;mico de 265&#215;149 cm (16:9), ofrece una visualizaci&oacute;n amplia y envolvente, ideal para aulas, oficinas o salas de reuniones. Su superficie de 4 capas mejora el contraste y la nitidez de la imagen, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/\" \/>\n<meta property=\"og:site_name\" content=\"Setnology\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T05:10:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2024\/07\/MPRPAY0056_800.jpg?fit=800%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/iggual-pantalla-electrica-169-110-243x137-cm\\\/\",\"url\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/iggual-pantalla-electrica-169-110-243x137-cm\\\/\",\"name\":\"iggual Pantalla el\u00e9ctrica 16:9 110\\\" 243x137 cm - Setnology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/iggual-pantalla-electrica-169-110-243x137-cm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/iggual-pantalla-electrica-169-110-243x137-cm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/MPRPAY0056_800.jpg?fit=800%2C800&ssl=1\",\"datePublished\":\"2026-07-11T04:10:04+00:00\",\"dateModified\":\"2026-07-11T05:10:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/iggual-pantalla-electrica-169-110-243x137-cm\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/iggual-pantalla-electrica-169-110-243x137-cm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/iggual-pantalla-electrica-169-110-243x137-cm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/MPRPAY0056_800.jpg?fit=800%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/MPRPAY0056_800.jpg?fit=800%2C800&ssl=1\",\"width\":800,\"height\":800,\"caption\":\"Pantallas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/iggual-pantalla-electrica-169-110-243x137-cm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/setnology.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"iggual Pantalla el\u00e9ctrica 16:9 110&#8243; 243&#215;137 cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#website\",\"url\":\"https:\\\/\\\/setnology.es\\\/\",\"name\":\"Setnology\",\"description\":\"Servicios de Expansi\u00f3n Tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/setnology.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#organization\",\"name\":\"Setnology\",\"url\":\"https:\\\/\\\/setnology.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1\",\"width\":995,\"height\":258,\"caption\":\"Setnology\"},\"image\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"iggual Pantalla el\u00e9ctrica 16:9 110\" 243x137 cm - Setnology","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/","og_locale":"es_ES","og_type":"article","og_title":"iggual Pantalla el\u00e9ctrica 16:9 110\" 243x137 cm","og_description":"La pantalla el&eacute;ctrica PSIES243 de iggual es una apuesta segura para quienes buscan calidad y comodidad en sus presentaciones. Con un formato panor&aacute;mico de 265&#215;149 cm (16:9), ofrece una visualizaci&oacute;n amplia y envolvente, ideal para aulas, oficinas o salas de reuniones. Su superficie de 4 capas mejora el contraste y la nitidez de la imagen, [&hellip;]","og_url":"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/","og_site_name":"Setnology","article_modified_time":"2026-07-11T05:10:38+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2024\/07\/MPRPAY0056_800.jpg?fit=800%2C800&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/","url":"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/","name":"iggual Pantalla el\u00e9ctrica 16:9 110\" 243x137 cm - Setnology","isPartOf":{"@id":"https:\/\/setnology.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/#primaryimage"},"image":{"@id":"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2024\/07\/MPRPAY0056_800.jpg?fit=800%2C800&ssl=1","datePublished":"2026-07-11T04:10:04+00:00","dateModified":"2026-07-11T05:10:38+00:00","breadcrumb":{"@id":"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/#primaryimage","url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2024\/07\/MPRPAY0056_800.jpg?fit=800%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2024\/07\/MPRPAY0056_800.jpg?fit=800%2C800&ssl=1","width":800,"height":800,"caption":"Pantallas"},{"@type":"BreadcrumbList","@id":"https:\/\/setnology.es\/index.php\/producto\/iggual-pantalla-electrica-169-110-243x137-cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/setnology.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/setnology.es\/index.php\/tienda\/"},{"@type":"ListItem","position":3,"name":"iggual Pantalla el\u00e9ctrica 16:9 110&#8243; 243&#215;137 cm"}]},{"@type":"WebSite","@id":"https:\/\/setnology.es\/#website","url":"https:\/\/setnology.es\/","name":"Setnology","description":"Servicios de Expansi\u00f3n Tecnol\u00f3gica","publisher":{"@id":"https:\/\/setnology.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/setnology.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/setnology.es\/#organization","name":"Setnology","url":"https:\/\/setnology.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/setnology.es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2021\/10\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1","contentUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2021\/10\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1","width":995,"height":258,"caption":"Setnology"},"image":{"@id":"https:\/\/setnology.es\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/205587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":3,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/205587\/revisions"}],"predecessor-version":[{"id":274667,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/205587\/revisions\/274667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/media\/205588"}],"wp:attachment":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/media?parent=205587"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_brand?post=205587"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_cat?post=205587"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_tag?post=205587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}