{"id":245134,"date":"2024-05-02T06:11:05","date_gmt":"2024-05-02T05:11:05","guid":{"rendered":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/"},"modified":"2026-07-14T12:10:34","modified_gmt":"2026-07-14T11:10:34","slug":"nanocable-cable-usb-2-0-impresora-ferrita-2-0-m","status":"publish","type":"product","link":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/","title":{"rendered":"Nanocable Cable USB 2.0 Impresora Ferrita  2.0 M"},"content":{"rendered":"<p style=\"text-align: left;\">Cable USB 2.0 especial para impresoras con conector tipo A macho en un extremo y B macho en el otro<\/p>\n<table class=\"tabla_caracteristicas k-table\" width=\"100%\">\n<tbody>\n<tr>\n<td><strong>Marca<\/strong><\/td>\n<td>NANOCABLE<\/td>\n<\/tr>\n<tr>\n<td><strong>Modelo<\/strong><\/td>\n<td><strong>10.01.1202<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>Caracteristicas<\/strong><\/td>\n<td>&#8211; Conectores de alta calidad blindados en oro de 24K, Doble apantallado y estructura (28AWG+24AWG) para obtener un excelente resultado en la transferencia de datos. Incluye adem&aacute;s ferrita en ambos extremos para evitar interferencias de alta frecuencia.<br \/>&#8211; Ideal para las conexiones m&aacute;s exigentes<br \/>&#8211; Longitud: 2.0 metros<br \/>&#8211; Color: Negro<br \/>&#8211; NormativaS: RoHS<br \/>&#8211; Test de Funcionamiento: 100% testado<br \/>Contenido<br \/>&#8211; 1 x Cable USB 2.0 impresora hq con ferrita, tipo a\/m-b\/m, negro, 2.0 m <\/td>\n<\/tr>\n<tr>\n<td><strong>Fecha de revisi&oacute;n<\/strong><\/td>\n<td>27-06-2019 por AVN<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Cable USB 2.0 especial para impresoras con conector tipo A macho en un extremo y B macho en el otro Marca NANOCABLE Modelo 10.01.1202 Caracteristicas &#8211; Conectores de alta calidad blindados en oro de 24K, Doble apantallado y estructura (28AWG+24AWG) para obtener un excelente resultado en la transferencia de datos. Incluye adem&aacute;s ferrita en ambos [&hellip;]<\/p>\n","protected":false},"featured_media":81558,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[1522,1524,1484],"product_tag":[565,650,564],"class_list":["post-245134","product","type-product","status-publish","has-post-thumbnail","product_cat-accesorios-impresora-escaner-dispositivos","product_cat-cables-impresora-escaner-accesorios-impresora-escaner-dispositivos","product_cat-dispositivos","product_tag-565","product_tag-aci","product_tag-nanocable","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nanocable Cable USB 2.0 Impresora Ferrita 2.0 M - Setnology<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nanocable Cable USB 2.0 Impresora Ferrita 2.0 M\" \/>\n<meta property=\"og:description\" content=\"Cable USB 2.0 especial para impresoras con conector tipo A macho en un extremo y B macho en el otro Marca NANOCABLE Modelo 10.01.1202 Caracteristicas &#8211; Conectores de alta calidad blindados en oro de 24K, Doble apantallado y estructura (28AWG+24AWG) para obtener un excelente resultado en la transferencia de datos. Incluye adem&aacute;s ferrita en ambos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/\" \/>\n<meta property=\"og:site_name\" content=\"Setnology\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T11:10:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/AIEACI0079_800.jpg?fit=800%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\\\/\",\"url\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\\\/\",\"name\":\"Nanocable Cable USB 2.0 Impresora Ferrita 2.0 M - Setnology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/AIEACI0079_800.jpg?fit=800%2C800&ssl=1\",\"datePublished\":\"2024-05-02T05:11:05+00:00\",\"dateModified\":\"2026-07-14T11:10:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/AIEACI0079_800.jpg?fit=800%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/AIEACI0079_800.jpg?fit=800%2C800&ssl=1\",\"width\":800,\"height\":800,\"caption\":\"Cables Impresora\\\/Esc\u00e1ner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/setnology.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nanocable Cable USB 2.0 Impresora Ferrita 2.0 M\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#website\",\"url\":\"https:\\\/\\\/setnology.es\\\/\",\"name\":\"Setnology\",\"description\":\"Servicios de Expansi\u00f3n Tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/setnology.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#organization\",\"name\":\"Setnology\",\"url\":\"https:\\\/\\\/setnology.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1\",\"width\":995,\"height\":258,\"caption\":\"Setnology\"},\"image\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nanocable Cable USB 2.0 Impresora Ferrita 2.0 M - Setnology","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/","og_locale":"es_ES","og_type":"article","og_title":"Nanocable Cable USB 2.0 Impresora Ferrita 2.0 M","og_description":"Cable USB 2.0 especial para impresoras con conector tipo A macho en un extremo y B macho en el otro Marca NANOCABLE Modelo 10.01.1202 Caracteristicas &#8211; Conectores de alta calidad blindados en oro de 24K, Doble apantallado y estructura (28AWG+24AWG) para obtener un excelente resultado en la transferencia de datos. Incluye adem&aacute;s ferrita en ambos [&hellip;]","og_url":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/","og_site_name":"Setnology","article_modified_time":"2026-07-14T11:10:34+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/AIEACI0079_800.jpg?fit=800%2C800&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/","url":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/","name":"Nanocable Cable USB 2.0 Impresora Ferrita 2.0 M - Setnology","isPartOf":{"@id":"https:\/\/setnology.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/#primaryimage"},"image":{"@id":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/AIEACI0079_800.jpg?fit=800%2C800&ssl=1","datePublished":"2024-05-02T05:11:05+00:00","dateModified":"2026-07-14T11:10:34+00:00","breadcrumb":{"@id":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/#primaryimage","url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/AIEACI0079_800.jpg?fit=800%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/AIEACI0079_800.jpg?fit=800%2C800&ssl=1","width":800,"height":800,"caption":"Cables Impresora\/Esc\u00e1ner"},{"@type":"BreadcrumbList","@id":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-usb-2-0-impresora-ferrita-2-0-m\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/setnology.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/setnology.es\/index.php\/tienda\/"},{"@type":"ListItem","position":3,"name":"Nanocable Cable USB 2.0 Impresora Ferrita 2.0 M"}]},{"@type":"WebSite","@id":"https:\/\/setnology.es\/#website","url":"https:\/\/setnology.es\/","name":"Setnology","description":"Servicios de Expansi\u00f3n Tecnol\u00f3gica","publisher":{"@id":"https:\/\/setnology.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/setnology.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/setnology.es\/#organization","name":"Setnology","url":"https:\/\/setnology.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/setnology.es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2021\/10\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1","contentUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2021\/10\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1","width":995,"height":258,"caption":"Setnology"},"image":{"@id":"https:\/\/setnology.es\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/245134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/245134\/revisions"}],"predecessor-version":[{"id":260812,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/245134\/revisions\/260812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/media\/81558"}],"wp:attachment":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/media?parent=245134"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_brand?post=245134"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_cat?post=245134"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_tag?post=245134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}