{"id":247371,"date":"2024-05-02T06:11:27","date_gmt":"2024-05-02T05:11:27","guid":{"rendered":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/"},"modified":"2026-07-15T11:10:20","modified_gmt":"2026-07-15T10:10:20","slug":"nanocable-cable-sata-molex-m-sata-h-16cm","status":"publish","type":"product","link":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/","title":{"rendered":"Nanocable Cable SATA, Molex M-SATA\/H, 16cm"},"content":{"rendered":"<p style=\"text-align: left;\"><\/p>\n<table class=\"tabla_caracteristicas k-table\" width=\"100%\">\n<tbody>\n<tr>\n<td><strong>Marca<\/strong><\/td>\n<td>NANOCABLE<\/td>\n<\/tr>\n<tr>\n<td><strong>Modelo<\/strong><\/td>\n<td><strong>10.19.0205-OEM<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\"><strong>Caracter&iacute;sticas<\/strong><\/td>\n<td>&#8211; Ideal para convertir un conector Molex 4 pin a un conector sata alimentaci&oacute;n<br \/>&#8211; Longitud: 16 cm<br \/>&#8211; NormativaS: RoHS<br \/>&#8211; Test de Funcionamiento: 100% testado<\/td>\n<\/tr>\n<tr>\n<td><strong>Fecha de revisi&oacute;n<\/strong><\/td>\n<td>26-10-2020 por MSB<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Marca NANOCABLE Modelo 10.19.0205-OEM Caracter&iacute;sticas &#8211; Ideal para convertir un conector Molex 4 pin a un conector sata alimentaci&oacute;n&#8211; Longitud: 16 cm&#8211; NormativaS: RoHS&#8211; Test de Funcionamiento: 100% testado Fecha de revisi&oacute;n 26-10-2020 por MSB<\/p>\n","protected":false},"featured_media":83615,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[1542,1545,1484],"product_tag":[565,709,564],"class_list":["post-247371","product","type-product","status-publish","has-post-thumbnail","product_cat-accesorios-pc-y-tpv-dispositivos","product_cat-cables-y-accesorios-pc-accesorios-pc-y-tpv-dispositivos","product_cat-dispositivos","product_tag-565","product_tag-apc","product_tag-nanocable","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nanocable Cable SATA, Molex M-SATA\/H, 16cm - Setnology<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nanocable Cable SATA, Molex M-SATA\/H, 16cm\" \/>\n<meta property=\"og:description\" content=\"Marca NANOCABLE Modelo 10.19.0205-OEM Caracter&iacute;sticas &#8211; Ideal para convertir un conector Molex 4 pin a un conector sata alimentaci&oacute;n&#8211; Longitud: 16 cm&#8211; NormativaS: RoHS&#8211; Test de Funcionamiento: 100% testado Fecha de revisi&oacute;n 26-10-2020 por MSB\" \/>\n<meta property=\"og:url\" content=\"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/\" \/>\n<meta property=\"og:site_name\" content=\"Setnology\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T10:10:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/APTAPC0765_800.jpg?fit=800%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-sata-molex-m-sata-h-16cm\\\/\",\"url\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-sata-molex-m-sata-h-16cm\\\/\",\"name\":\"Nanocable Cable SATA, Molex M-SATA\\\/H, 16cm - Setnology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-sata-molex-m-sata-h-16cm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-sata-molex-m-sata-h-16cm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/APTAPC0765_800.jpg?fit=800%2C800&ssl=1\",\"datePublished\":\"2024-05-02T05:11:27+00:00\",\"dateModified\":\"2026-07-15T10:10:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-sata-molex-m-sata-h-16cm\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-sata-molex-m-sata-h-16cm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-sata-molex-m-sata-h-16cm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/APTAPC0765_800.jpg?fit=800%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/APTAPC0765_800.jpg?fit=800%2C800&ssl=1\",\"width\":800,\"height\":800,\"caption\":\"Cables y Accesorios PC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/nanocable-cable-sata-molex-m-sata-h-16cm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/setnology.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nanocable Cable SATA, Molex M-SATA\\\/H, 16cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#website\",\"url\":\"https:\\\/\\\/setnology.es\\\/\",\"name\":\"Setnology\",\"description\":\"Servicios de Expansi\u00f3n Tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/setnology.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#organization\",\"name\":\"Setnology\",\"url\":\"https:\\\/\\\/setnology.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1\",\"width\":995,\"height\":258,\"caption\":\"Setnology\"},\"image\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nanocable Cable SATA, Molex M-SATA\/H, 16cm - Setnology","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/","og_locale":"es_ES","og_type":"article","og_title":"Nanocable Cable SATA, Molex M-SATA\/H, 16cm","og_description":"Marca NANOCABLE Modelo 10.19.0205-OEM Caracter&iacute;sticas &#8211; Ideal para convertir un conector Molex 4 pin a un conector sata alimentaci&oacute;n&#8211; Longitud: 16 cm&#8211; NormativaS: RoHS&#8211; Test de Funcionamiento: 100% testado Fecha de revisi&oacute;n 26-10-2020 por MSB","og_url":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/","og_site_name":"Setnology","article_modified_time":"2026-07-15T10:10:20+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/APTAPC0765_800.jpg?fit=800%2C800&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/","url":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/","name":"Nanocable Cable SATA, Molex M-SATA\/H, 16cm - Setnology","isPartOf":{"@id":"https:\/\/setnology.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/#primaryimage"},"image":{"@id":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/APTAPC0765_800.jpg?fit=800%2C800&ssl=1","datePublished":"2024-05-02T05:11:27+00:00","dateModified":"2026-07-15T10:10:20+00:00","breadcrumb":{"@id":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/#primaryimage","url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/APTAPC0765_800.jpg?fit=800%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/APTAPC0765_800.jpg?fit=800%2C800&ssl=1","width":800,"height":800,"caption":"Cables y Accesorios PC"},{"@type":"BreadcrumbList","@id":"https:\/\/setnology.es\/index.php\/producto\/nanocable-cable-sata-molex-m-sata-h-16cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/setnology.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/setnology.es\/index.php\/tienda\/"},{"@type":"ListItem","position":3,"name":"Nanocable Cable SATA, Molex M-SATA\/H, 16cm"}]},{"@type":"WebSite","@id":"https:\/\/setnology.es\/#website","url":"https:\/\/setnology.es\/","name":"Setnology","description":"Servicios de Expansi\u00f3n Tecnol\u00f3gica","publisher":{"@id":"https:\/\/setnology.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/setnology.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/setnology.es\/#organization","name":"Setnology","url":"https:\/\/setnology.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/setnology.es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2021\/10\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1","contentUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2021\/10\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1","width":995,"height":258,"caption":"Setnology"},"image":{"@id":"https:\/\/setnology.es\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/247371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/247371\/revisions"}],"predecessor-version":[{"id":262036,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/247371\/revisions\/262036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/media\/83615"}],"wp:attachment":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/media?parent=247371"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_brand?post=247371"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_cat?post=247371"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_tag?post=247371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}