{"id":250477,"date":"2024-05-02T06:04:13","date_gmt":"2024-05-02T05:04:13","guid":{"rendered":"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/"},"modified":"2026-07-13T17:10:21","modified_gmt":"2026-07-13T16:10:21","slug":"ewent-ew2528-mochila-portatil-17-3","status":"publish","type":"product","link":"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/","title":{"rendered":"EWENT EW2528 Mochila port\u00e1til 17.3&#8243;"},"content":{"rendered":"<p style=\"text-align: left;\">Proteja su ordenador port&aacute;til con el <strong>EWENT EW2528<\/strong> de <strong>17,3<\/strong> pulgadas <strong>Urban Notebook Backpack<\/strong>. El revestimiento interior de doble protege su port&aacute;til de ara&ntilde;azos y otros da&ntilde;os. El <strong>EW2528<\/strong> est&aacute; equipado con compartimentos especiales para su tableta, documentos, adaptador de corriente, rat&oacute;n y otros perif&eacute;ricos. La mochila para port&aacute;til urbano est&aacute; dise&ntilde;ado para el uso diario gracias al panel trasero acolchado, el material repelente al agua y ajustable.<br \/>&nbsp;<\/p>\n<table class=\"tabla_caracteristicas k-table\" width=\"100%\">\n<tr>\n<td><strong>Marca<\/strong><\/td>\n<td>Ewent<\/td>\n<\/tr>\n<tr>\n<td><strong>Modelo<\/strong><\/td>\n<td><strong>EW2528<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>Caracter&iacute;sticas<\/strong><\/td>\n<td>&#8211; Adecuado para port&aacute;tiles de hasta 17,3 pulgadas<br \/>\t\t\t&#8211; Doble forro interior para una mejor protecci&oacute;n de su ordenador port&aacute;til<br \/>\t\t\t&#8211; Mochila grande con suficiente espacio de almacenamiento gracias a los 5 compartimentos principales<br \/>\t\t\t&#8211; Compartimento para el port&aacute;til con compartimento adicional para guardar su tableta<br \/>\t\t\t&#8211; Compartimento adicional con el organizador conveniente para guardar accesorios<br \/>\t\t\t&#8211; Correas ergon&oacute;micas de hombro ajustable y respaldo acolchado para mayor comodidad<\/td>\n<\/tr>\n<tr>\n<td><strong>Especificaciones<\/strong><\/td>\n<td>&#8211; El material utilizado es a prueba de agua<br \/>\t\t\t&#8211; Material: 900D Gucci polyester<br \/>\t\t\t&#8211; Dimensiones: 43 x 50 x 14 cm<br \/>\t\t\t&#8211; Compartimento para p&oacute;rtatil: 31 x 46 x 4cm<br \/>\t\t\t&#8211; M&aacute;x. tama&ntilde;o de compartimento para tablet: 10&quot;\u0092\u0092<br \/>\t\t\t&#8211; Volumen: 30L<br \/>\t\t\t&#8211; Peso: 870g<\/td>\n<\/tr>\n<tr>\n<td><strong>Fecha de revisi&oacute;n<\/strong><\/td>\n<td>06-05-2021 por MPM<\/td>\n<\/tr>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Proteja su ordenador port&aacute;til con el EWENT EW2528 de 17,3 pulgadas Urban Notebook Backpack. El revestimiento interior de doble protege su port&aacute;til de ara&ntilde;azos y otros da&ntilde;os. El EW2528 est&aacute; equipado con compartimentos especiales para su tableta, documentos, adaptador de corriente, rat&oacute;n y otros perif&eacute;ricos. La mochila para port&aacute;til urbano est&aacute; dise&ntilde;ado para el uso [&hellip;]<\/p>\n","protected":false},"featured_media":80258,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[1490,1493,1484],"product_tag":[1389,550,521],"class_list":["post-250477","product","type-product","status-publish","has-post-thumbnail","product_cat-accesorios-portatil-dispositivos","product_cat-bolsas-transporte-accesorios-portatil-dispositivos","product_cat-dispositivos","product_tag-1389","product_tag-abt","product_tag-ewent","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>EWENT EW2528 Mochila port\u00e1til 17.3&quot; - Setnology<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EWENT EW2528 Mochila port\u00e1til 17.3&quot;\" \/>\n<meta property=\"og:description\" content=\"Proteja su ordenador port&aacute;til con el EWENT EW2528 de 17,3 pulgadas Urban Notebook Backpack. El revestimiento interior de doble protege su port&aacute;til de ara&ntilde;azos y otros da&ntilde;os. El EW2528 est&aacute; equipado con compartimentos especiales para su tableta, documentos, adaptador de corriente, rat&oacute;n y otros perif&eacute;ricos. La mochila para port&aacute;til urbano est&aacute; dise&ntilde;ado para el uso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Setnology\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T16:10:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/AAOABT0532_800.jpg?fit=800%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/ewent-ew2528-mochila-portatil-17-3\\\/\",\"url\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/ewent-ew2528-mochila-portatil-17-3\\\/\",\"name\":\"EWENT EW2528 Mochila port\u00e1til 17.3\\\" - Setnology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/ewent-ew2528-mochila-portatil-17-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/ewent-ew2528-mochila-portatil-17-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/AAOABT0532_800.jpg?fit=800%2C800&ssl=1\",\"datePublished\":\"2024-05-02T05:04:13+00:00\",\"dateModified\":\"2026-07-13T16:10:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/ewent-ew2528-mochila-portatil-17-3\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/ewent-ew2528-mochila-portatil-17-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/ewent-ew2528-mochila-portatil-17-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/AAOABT0532_800.jpg?fit=800%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/AAOABT0532_800.jpg?fit=800%2C800&ssl=1\",\"width\":800,\"height\":800,\"caption\":\"Bolsas Transporte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/producto\\\/ewent-ew2528-mochila-portatil-17-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/setnology.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/setnology.es\\\/index.php\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EWENT EW2528 Mochila port\u00e1til 17.3&#8243;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#website\",\"url\":\"https:\\\/\\\/setnology.es\\\/\",\"name\":\"Setnology\",\"description\":\"Servicios de Expansi\u00f3n Tecnol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/setnology.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#organization\",\"name\":\"Setnology\",\"url\":\"https:\\\/\\\/setnology.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/setnology.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/setnology.es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1\",\"width\":995,\"height\":258,\"caption\":\"Setnology\"},\"image\":{\"@id\":\"https:\\\/\\\/setnology.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EWENT EW2528 Mochila port\u00e1til 17.3\" - Setnology","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/","og_locale":"es_ES","og_type":"article","og_title":"EWENT EW2528 Mochila port\u00e1til 17.3\"","og_description":"Proteja su ordenador port&aacute;til con el EWENT EW2528 de 17,3 pulgadas Urban Notebook Backpack. El revestimiento interior de doble protege su port&aacute;til de ara&ntilde;azos y otros da&ntilde;os. El EW2528 est&aacute; equipado con compartimentos especiales para su tableta, documentos, adaptador de corriente, rat&oacute;n y otros perif&eacute;ricos. La mochila para port&aacute;til urbano est&aacute; dise&ntilde;ado para el uso [&hellip;]","og_url":"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/","og_site_name":"Setnology","article_modified_time":"2026-07-13T16:10:21+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/AAOABT0532_800.jpg?fit=800%2C800&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/","url":"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/","name":"EWENT EW2528 Mochila port\u00e1til 17.3\" - Setnology","isPartOf":{"@id":"https:\/\/setnology.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/#primaryimage"},"image":{"@id":"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/AAOABT0532_800.jpg?fit=800%2C800&ssl=1","datePublished":"2024-05-02T05:04:13+00:00","dateModified":"2026-07-13T16:10:21+00:00","breadcrumb":{"@id":"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/#primaryimage","url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/AAOABT0532_800.jpg?fit=800%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2022\/07\/AAOABT0532_800.jpg?fit=800%2C800&ssl=1","width":800,"height":800,"caption":"Bolsas Transporte"},{"@type":"BreadcrumbList","@id":"https:\/\/setnology.es\/index.php\/producto\/ewent-ew2528-mochila-portatil-17-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/setnology.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/setnology.es\/index.php\/tienda\/"},{"@type":"ListItem","position":3,"name":"EWENT EW2528 Mochila port\u00e1til 17.3&#8243;"}]},{"@type":"WebSite","@id":"https:\/\/setnology.es\/#website","url":"https:\/\/setnology.es\/","name":"Setnology","description":"Servicios de Expansi\u00f3n Tecnol\u00f3gica","publisher":{"@id":"https:\/\/setnology.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/setnology.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/setnology.es\/#organization","name":"Setnology","url":"https:\/\/setnology.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/setnology.es\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2021\/10\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1","contentUrl":"https:\/\/i0.wp.com\/setnology.es\/wp-content\/uploads\/2021\/10\/cropped-Logo-Blanco-1.png?fit=995%2C258&ssl=1","width":995,"height":258,"caption":"Setnology"},"image":{"@id":"https:\/\/setnology.es\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/250477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/250477\/revisions"}],"predecessor-version":[{"id":259796,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product\/250477\/revisions\/259796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/media\/80258"}],"wp:attachment":[{"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/media?parent=250477"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_brand?post=250477"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_cat?post=250477"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/setnology.es\/index.php\/wp-json\/wp\/v2\/product_tag?post=250477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}